{"id":22762,"date":"2023-10-23T14:30:58","date_gmt":"2023-10-23T13:30:58","guid":{"rendered":"https:\/\/www.g4f-records.com\/?p=22762"},"modified":"2023-10-24T14:43:43","modified_gmt":"2023-10-24T13:43:43","slug":"endless-dungeon-original-game-soundtrack-available-on-digital-and-vinyl-edition","status":"publish","type":"post","link":"https:\/\/www.g4f-records.com\/en\/endless-dungeon-original-game-soundtrack-available-on-digital-and-vinyl-edition-22762\/","title":{"rendered":"ENDLESS\u2122 Dungeon (Original Game Soundtrack) available on Digital and Vinyl Edition."},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">The new ENDLESS\u2122 Dungeon (Original Game Soundtrack) album is available on all music platforms!<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><a href=\"https:\/\/idol-io.ffm.to\/endlessdungeonogs\" target=\"_blank\" rel=\"noreferrer noopener\">STREAMING &#8211; ENDLESS\u2122 Dungeon (Original Game Soundtrack)<\/a><\/strong><\/h3>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-spotify wp-block-embed-spotify wp-embed-aspect-21-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Spotify Embed: Endless Dungeon (Original Game Soundtrack)\" style=\"border-radius: 12px\" width=\"100%\" height=\"352\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/album\/76c6oS9gr3bUkEXZR8KmJw?si=3OEKzhi2Sc-awVJBgJMmSA&amp;utm_source=oembed\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><a href=\"https:\/\/idol-io.ffm.to\/endlessdungeonogs\" target=\"_blank\" rel=\"noreferrer noopener\">STREAMING &#8211; ENDLESS\u2122 Dungeon (Original Game Soundtrack)<\/a><\/strong><\/h3>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p style=\"font-size:18px; line-height:29px;\">The interactive original soundtrack from ENDLESS\u2122 Dungeon has been composed by the Amplitude Studios resident composer Arnaud Roy (HUMANKIND\u2122, ENDLESS\u2122 Space, ENDLESS\u2122 Legend) and by the singer-songwriter Lera Lynn (HBO&#8217;s True Detective). A space western album that featured folk, progressive rock and a unique blend of 90s synthesizers.<\/p>\n\n\n\n<p style=\"font-size:18px; line-height:29px;\">In addition to the album being available on all platforms, (<a href=\"https:\/\/open.spotify.com\/album\/76c6oS9gr3bUkEXZR8KmJw?si=uBELWwmJSbOUcVN0tqcLPw\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Spotify<\/strong><\/a>, <a href=\"https:\/\/www.youtube.com\/watch?v=6bTcktIG6wM&#038;list=PLtzah_dj5hUUn0wJrnnVNydIIvNLA_3qX\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>YouTube<\/strong><\/a>, <a href=\"https:\/\/music.apple.com\/us\/album\/endless-dungeon-original-game-soundtrack\/1708437309\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Apple Music<\/strong><\/a>&#8230;), live performances of the songs \u201cFree Again\u201d and \u201cThe Garden\u201d, performed by Lera Lynn are available on the <a href=\"https:\/\/www.youtube.com\/@EndlessUniverse\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Endless Universe<\/strong><\/a> YouTube channel.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"512\" src=\"https:\/\/www.g4f-records.com\/wp-content\/uploads\/2023\/10\/Arnaud-Studio-2023resize-1024x512.webp\" alt=\"Arnaud Roy\" class=\"wp-image-22747\" srcset=\"https:\/\/www.g4f-records.com\/wp-content\/uploads\/2023\/10\/Arnaud-Studio-2023resize-1024x512.webp 1024w, https:\/\/www.g4f-records.com\/wp-content\/uploads\/2023\/10\/Arnaud-Studio-2023resize-200x100.webp 200w, https:\/\/www.g4f-records.com\/wp-content\/uploads\/2023\/10\/Arnaud-Studio-2023resize-1536x768.webp 1536w, https:\/\/www.g4f-records.com\/wp-content\/uploads\/2023\/10\/Arnaud-Studio-2023resize-600x300.webp 600w, https:\/\/www.g4f-records.com\/wp-content\/uploads\/2023\/10\/Arnaud-Studio-2023resize-jpg.webp 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p style=\"font-size:23px; line-height:50px;\"><em>\u201cI composed the soundtrack for Endless Dungeon with the desire to create a unique blend of 90s synthesizers and a progressive rock band. I was greatly inspired by artists from that era such as Tortoise and M\u00f9m. By combining the iconic synths from previous game of the Endless series, a guitar lost in space, and a groovy drumbeat, I tried to create a space western atmosphere ideal for exploring the station and engaging in epic battles with monsters.\u201d<\/em><\/p><figure><blockquote><cite>Arnaud Roy<\/cite><\/blockquote><\/figure>\n\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p style=\"font-size:18px; line-height:29px;\">The soundtrack is also available for pre-order in a double vinyl edition, featuring a gold marble 2xLP. This edition includes a selection of 19 tracks from the original soundtrack of the game. The pre-orders are available on the G4F Records store (estimating shipping date: Fabruary 2024).<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><a href=\"https:\/\/www.g4f-records.com\/en\/produit\/endless-dungeon-vinyl-edition\/\" target=\"_blank\" rel=\"noreferrer noopener\">PRE-ORDER THE VINYL<\/a><\/strong><\/h3>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.g4f-records.com\/en\/produit\/endless-dungeon-vinyl-edition\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"486\" src=\"https:\/\/www.g4f-records.com\/wp-content\/uploads\/2023\/10\/EndlessDungeonVinyl_MockupArticle-1024x486.png\" alt=\"Endless Dungeon - Vinyl Edition\" class=\"wp-image-22736\" srcset=\"https:\/\/www.g4f-records.com\/wp-content\/uploads\/2023\/10\/EndlessDungeonVinyl_MockupArticle-1024x486.png 1024w, https:\/\/www.g4f-records.com\/wp-content\/uploads\/2023\/10\/EndlessDungeonVinyl_MockupArticle-200x95.png 200w, https:\/\/www.g4f-records.com\/wp-content\/uploads\/2023\/10\/EndlessDungeonVinyl_MockupArticle-1536x729.png 1536w, https:\/\/www.g4f-records.com\/wp-content\/uploads\/2023\/10\/EndlessDungeonVinyl_MockupArticle-2048x973.png 2048w, https:\/\/www.g4f-records.com\/wp-content\/uploads\/2023\/10\/EndlessDungeonVinyl_MockupArticle-250x120.png 250w, https:\/\/www.g4f-records.com\/wp-content\/uploads\/2023\/10\/EndlessDungeonVinyl_MockupArticle-600x285.png 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p style=\"font-size:18px; line-height:29px;\">ENDLESS\u2122 Dungeon is a tactical action rogue-lite game with a twist of tower defense. Play alone or with up to two friends in co-op as you try to make your way through the mysterious space station on which you find yourselves trapped.\n\nProtect your crystal from waves of oncoming monsters. If it dies, you die, so be careful!\n<a href=\"https:\/\/endlessdungeon.game\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>ENDLESS\u2122 Dungeon is now available on PC and consoles<\/strong><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>The new ENDLESS\u2122 Dungeon (Original Game Soundtrack) album is available on all music platforms! STREAMING &#8211; ENDLESS\u2122 Dungeon (Original Game Soundtrack) STREAMING &#8230;<\/p>\n","protected":false},"author":3,"featured_media":22754,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[118],"tags":[],"class_list":["post-22762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ENDLESS\u2122 Dungeon (Original Game Soundtrack) available on Digital and Vinyl Edition. - G4F Records<\/title>\n<meta name=\"description\" content=\"The new ENDLESS\u2122 Dungeon (Original Game Soundtrack) is now available on all music platforms! Arnaud Roy &amp; Lera Lynn...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.g4f-records.com\/en\/endless-dungeon-original-game-soundtrack-available-on-digital-and-vinyl-edition-22762\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ENDLESS\u2122 Dungeon (Original Game Soundtrack) available on Digital and Vinyl Edition. - G4F Records\" \/>\n<meta property=\"og:description\" content=\"The new ENDLESS\u2122 Dungeon (Original Game Soundtrack) is now available on all music platforms! Arnaud Roy &amp; Lera Lynn...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.g4f-records.com\/en\/endless-dungeon-original-game-soundtrack-available-on-digital-and-vinyl-edition-22762\/\" \/>\n<meta property=\"og:site_name\" content=\"G4F Records\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.twitter.com\/G4F_Records\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-23T13:30:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-24T13:43:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.g4f-records.com\/wp-content\/uploads\/2023\/10\/Header-1180x500.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Vincent\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@G4F_Records\" \/>\n<meta name=\"twitter:site\" content=\"@G4F_Records\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vincent\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.g4f-records.com\\\/en\\\/endless-dungeon-original-game-soundtrack-available-on-digital-and-vinyl-edition-22762\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.g4f-records.com\\\/en\\\/endless-dungeon-original-game-soundtrack-available-on-digital-and-vinyl-edition-22762\\\/\"},\"author\":{\"name\":\"Vincent\",\"@id\":\"https:\\\/\\\/www.g4f-records.com\\\/en\\\/#\\\/schema\\\/person\\\/96f18ec3e1a00406480fdf37e6e8688b\"},\"headline\":\"ENDLESS\u2122 Dungeon (Original Game Soundtrack) available on Digital and Vinyl Edition.\",\"datePublished\":\"2023-10-23T13:30:58+00:00\",\"dateModified\":\"2023-10-24T13:43:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.g4f-records.com\\\/en\\\/endless-dungeon-original-game-soundtrack-available-on-digital-and-vinyl-edition-22762\\\/\"},\"wordCount\":333,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.g4f-records.com\\\/en\\\/endless-dungeon-original-game-soundtrack-available-on-digital-and-vinyl-edition-22762\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.g4f-records.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Header-1180x500.webp\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.g4f-records.com\\\/en\\\/endless-dungeon-original-game-soundtrack-available-on-digital-and-vinyl-edition-22762\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.g4f-records.com\\\/en\\\/endless-dungeon-original-game-soundtrack-available-on-digital-and-vinyl-edition-22762\\\/\",\"url\":\"https:\\\/\\\/www.g4f-records.com\\\/en\\\/endless-dungeon-original-game-soundtrack-available-on-digital-and-vinyl-edition-22762\\\/\",\"name\":\"ENDLESS\u2122 Dungeon (Original Game Soundtrack) available on Digital and Vinyl Edition. - G4F Records\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.g4f-records.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.g4f-records.com\\\/en\\\/endless-dungeon-original-game-soundtrack-available-on-digital-and-vinyl-edition-22762\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.g4f-records.com\\\/en\\\/endless-dungeon-original-game-soundtrack-available-on-digital-and-vinyl-edition-22762\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.g4f-records.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Header-1180x500.webp\",\"datePublished\":\"2023-10-23T13:30:58+00:00\",\"dateModified\":\"2023-10-24T13:43:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.g4f-records.com\\\/en\\\/#\\\/schema\\\/person\\\/96f18ec3e1a00406480fdf37e6e8688b\"},\"description\":\"The new ENDLESS\u2122 Dungeon (Original Game Soundtrack) is now available on all music platforms! Arnaud Roy & Lera Lynn...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.g4f-records.com\\\/en\\\/endless-dungeon-original-game-soundtrack-available-on-digital-and-vinyl-edition-22762\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.g4f-records.com\\\/en\\\/endless-dungeon-original-game-soundtrack-available-on-digital-and-vinyl-edition-22762\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.g4f-records.com\\\/en\\\/endless-dungeon-original-game-soundtrack-available-on-digital-and-vinyl-edition-22762\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.g4f-records.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Header-1180x500.webp\",\"contentUrl\":\"https:\\\/\\\/www.g4f-records.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Header-1180x500.webp\",\"width\":1920,\"height\":700,\"caption\":\"Endless Dungeon - Blog Header\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.g4f-records.com\\\/en\\\/endless-dungeon-original-game-soundtrack-available-on-digital-and-vinyl-edition-22762\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.g4f-records.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ENDLESS\u2122 Dungeon (Original Game Soundtrack) available on Digital and Vinyl Edition.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.g4f-records.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.g4f-records.com\\\/en\\\/\",\"name\":\"G4F Records\",\"description\":\"SOUNDTRACK MUSIC LABEL\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.g4f-records.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.g4f-records.com\\\/en\\\/#\\\/schema\\\/person\\\/96f18ec3e1a00406480fdf37e6e8688b\",\"name\":\"Vincent\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44bd3f86b0c4eb955fb9cb36cfb9a3b8a47c4f2a238bfabea1633e5de088e304?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44bd3f86b0c4eb955fb9cb36cfb9a3b8a47c4f2a238bfabea1633e5de088e304?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/44bd3f86b0c4eb955fb9cb36cfb9a3b8a47c4f2a238bfabea1633e5de088e304?s=96&d=mm&r=g\",\"caption\":\"Vincent\"},\"url\":\"https:\\\/\\\/www.g4f-records.com\\\/en\\\/author\\\/vincent\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ENDLESS\u2122 Dungeon (Original Game Soundtrack) available on Digital and Vinyl Edition. - G4F Records","description":"The new ENDLESS\u2122 Dungeon (Original Game Soundtrack) is now available on all music platforms! Arnaud Roy & Lera Lynn...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.g4f-records.com\/en\/endless-dungeon-original-game-soundtrack-available-on-digital-and-vinyl-edition-22762\/","og_locale":"en_US","og_type":"article","og_title":"ENDLESS\u2122 Dungeon (Original Game Soundtrack) available on Digital and Vinyl Edition. - G4F Records","og_description":"The new ENDLESS\u2122 Dungeon (Original Game Soundtrack) is now available on all music platforms! Arnaud Roy & Lera Lynn...","og_url":"https:\/\/www.g4f-records.com\/en\/endless-dungeon-original-game-soundtrack-available-on-digital-and-vinyl-edition-22762\/","og_site_name":"G4F Records","article_publisher":"http:\/\/www.twitter.com\/G4F_Records\/","article_published_time":"2023-10-23T13:30:58+00:00","article_modified_time":"2023-10-24T13:43:43+00:00","og_image":[{"width":1920,"height":700,"url":"https:\/\/www.g4f-records.com\/wp-content\/uploads\/2023\/10\/Header-1180x500.webp","type":"image\/jpeg"}],"author":"Vincent","twitter_card":"summary_large_image","twitter_creator":"@G4F_Records","twitter_site":"@G4F_Records","twitter_misc":{"Written by":"Vincent","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.g4f-records.com\/en\/endless-dungeon-original-game-soundtrack-available-on-digital-and-vinyl-edition-22762\/#article","isPartOf":{"@id":"https:\/\/www.g4f-records.com\/en\/endless-dungeon-original-game-soundtrack-available-on-digital-and-vinyl-edition-22762\/"},"author":{"name":"Vincent","@id":"https:\/\/www.g4f-records.com\/en\/#\/schema\/person\/96f18ec3e1a00406480fdf37e6e8688b"},"headline":"ENDLESS\u2122 Dungeon (Original Game Soundtrack) available on Digital and Vinyl Edition.","datePublished":"2023-10-23T13:30:58+00:00","dateModified":"2023-10-24T13:43:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.g4f-records.com\/en\/endless-dungeon-original-game-soundtrack-available-on-digital-and-vinyl-edition-22762\/"},"wordCount":333,"commentCount":0,"image":{"@id":"https:\/\/www.g4f-records.com\/en\/endless-dungeon-original-game-soundtrack-available-on-digital-and-vinyl-edition-22762\/#primaryimage"},"thumbnailUrl":"https:\/\/www.g4f-records.com\/wp-content\/uploads\/2023\/10\/Header-1180x500.webp","articleSection":["News"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.g4f-records.com\/en\/endless-dungeon-original-game-soundtrack-available-on-digital-and-vinyl-edition-22762\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.g4f-records.com\/en\/endless-dungeon-original-game-soundtrack-available-on-digital-and-vinyl-edition-22762\/","url":"https:\/\/www.g4f-records.com\/en\/endless-dungeon-original-game-soundtrack-available-on-digital-and-vinyl-edition-22762\/","name":"ENDLESS\u2122 Dungeon (Original Game Soundtrack) available on Digital and Vinyl Edition. - G4F Records","isPartOf":{"@id":"https:\/\/www.g4f-records.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.g4f-records.com\/en\/endless-dungeon-original-game-soundtrack-available-on-digital-and-vinyl-edition-22762\/#primaryimage"},"image":{"@id":"https:\/\/www.g4f-records.com\/en\/endless-dungeon-original-game-soundtrack-available-on-digital-and-vinyl-edition-22762\/#primaryimage"},"thumbnailUrl":"https:\/\/www.g4f-records.com\/wp-content\/uploads\/2023\/10\/Header-1180x500.webp","datePublished":"2023-10-23T13:30:58+00:00","dateModified":"2023-10-24T13:43:43+00:00","author":{"@id":"https:\/\/www.g4f-records.com\/en\/#\/schema\/person\/96f18ec3e1a00406480fdf37e6e8688b"},"description":"The new ENDLESS\u2122 Dungeon (Original Game Soundtrack) is now available on all music platforms! Arnaud Roy & Lera Lynn...","breadcrumb":{"@id":"https:\/\/www.g4f-records.com\/en\/endless-dungeon-original-game-soundtrack-available-on-digital-and-vinyl-edition-22762\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.g4f-records.com\/en\/endless-dungeon-original-game-soundtrack-available-on-digital-and-vinyl-edition-22762\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.g4f-records.com\/en\/endless-dungeon-original-game-soundtrack-available-on-digital-and-vinyl-edition-22762\/#primaryimage","url":"https:\/\/www.g4f-records.com\/wp-content\/uploads\/2023\/10\/Header-1180x500.webp","contentUrl":"https:\/\/www.g4f-records.com\/wp-content\/uploads\/2023\/10\/Header-1180x500.webp","width":1920,"height":700,"caption":"Endless Dungeon - Blog Header"},{"@type":"BreadcrumbList","@id":"https:\/\/www.g4f-records.com\/en\/endless-dungeon-original-game-soundtrack-available-on-digital-and-vinyl-edition-22762\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.g4f-records.com\/en\/"},{"@type":"ListItem","position":2,"name":"ENDLESS\u2122 Dungeon (Original Game Soundtrack) available on Digital and Vinyl Edition."}]},{"@type":"WebSite","@id":"https:\/\/www.g4f-records.com\/en\/#website","url":"https:\/\/www.g4f-records.com\/en\/","name":"G4F Records","description":"SOUNDTRACK MUSIC LABEL","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.g4f-records.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.g4f-records.com\/en\/#\/schema\/person\/96f18ec3e1a00406480fdf37e6e8688b","name":"Vincent","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/44bd3f86b0c4eb955fb9cb36cfb9a3b8a47c4f2a238bfabea1633e5de088e304?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/44bd3f86b0c4eb955fb9cb36cfb9a3b8a47c4f2a238bfabea1633e5de088e304?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/44bd3f86b0c4eb955fb9cb36cfb9a3b8a47c4f2a238bfabea1633e5de088e304?s=96&d=mm&r=g","caption":"Vincent"},"url":"https:\/\/www.g4f-records.com\/en\/author\/vincent\/"}]}},"_links":{"self":[{"href":"https:\/\/www.g4f-records.com\/en\/wp-json\/wp\/v2\/posts\/22762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.g4f-records.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.g4f-records.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.g4f-records.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.g4f-records.com\/en\/wp-json\/wp\/v2\/comments?post=22762"}],"version-history":[{"count":1,"href":"https:\/\/www.g4f-records.com\/en\/wp-json\/wp\/v2\/posts\/22762\/revisions"}],"predecessor-version":[{"id":22763,"href":"https:\/\/www.g4f-records.com\/en\/wp-json\/wp\/v2\/posts\/22762\/revisions\/22763"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.g4f-records.com\/en\/wp-json\/wp\/v2\/media\/22754"}],"wp:attachment":[{"href":"https:\/\/www.g4f-records.com\/en\/wp-json\/wp\/v2\/media?parent=22762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.g4f-records.com\/en\/wp-json\/wp\/v2\/categories?post=22762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.g4f-records.com\/en\/wp-json\/wp\/v2\/tags?post=22762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}